{"id":3480,"count":1,"description":"","link":"https:\/\/digitalmarketingdeal.com\/blog\/category\/music-schools\/","name":"Music Schools","slug":"music-schools","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/digitalmarketingdeal.com\/blog\/wp-json\/wp\/v2\/categories\/3480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digitalmarketingdeal.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/digitalmarketingdeal.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/digitalmarketingdeal.com\/blog\/wp-json\/wp\/v2\/posts?categories=3480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}